{"id":294636,"date":"2021-02-23T10:04:20","date_gmt":"2021-02-23T09:04:20","guid":{"rendered":"https:\/\/alders.p3group.de\/glossar\/drucktaster\/"},"modified":"2026-05-26T13:52:58","modified_gmt":"2026-05-26T11:52:58","slug":"bouton-poussoir","status":"publish","type":"glossary","link":"https:\/\/alders.de\/fr\/glossar\/bouton-poussoir\/","title":{"rendered":"Bouton-poussoir"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb el_class=\u00a0\u00bbsection-grauverlauf\u00a0\u00bb][vc_column][vc_column_text]<\/p>\n<h1 style=\"text-align: center;\">Drucktaster<\/h1>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner][vc_column_text]<a href=\"https:\/\/alders.de\/wp-content\/uploads\/2021\/02\/p9-OTTO-Controls-Schalter.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-290541\" src=\"https:\/\/alders.de\/wp-content\/uploads\/2021\/02\/p9-OTTO-Controls-Schalter-280x300.png\" alt=\"P9 OTTO Drucktaster ALDERS\" width=\"280\" height=\"300\" srcset=\"https:\/\/alders.de\/wp-content\/uploads\/2021\/02\/p9-OTTO-Controls-Schalter-280x300.png 280w, https:\/\/alders.de\/wp-content\/uploads\/2021\/02\/p9-OTTO-Controls-Schalter-600x643.png 600w, https:\/\/alders.de\/wp-content\/uploads\/2021\/02\/p9-OTTO-Controls-Schalter-955x1024.png 955w, https:\/\/alders.de\/wp-content\/uploads\/2021\/02\/p9-OTTO-Controls-Schalter-768x823.png 768w, https:\/\/alders.de\/wp-content\/uploads\/2021\/02\/p9-OTTO-Controls-Schalter.png 1000w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/><\/a><\/p>\n<p>Bei einem Drucktaster handelt es sich um ein Bedienelement, das bei einer manuellen Schaltung einen Stromkreis \u00f6ffnet oder schlie\u00dft. Ein sogenannter Schlie\u00dfer stellt dementsprechend die Verbindung zwischen zwei Kontakten her, w\u00e4hrend ein \u00d6ffner diese l\u00f6st. Nach dem Bet\u00e4tigen kehrt der Drucktaster stets in seine Ausgangslage zur\u00fcck. Die dahinterliegende Funktion wird nur solange ausgef\u00fchrt, wie der Taster gedr\u00fcckt wird.<\/p>\n<p>Drucktaster\u00a0kommen f\u00fcr vielf\u00e4ltige Aufgaben infrage und werden sowohl in privaten als auch gewerblichen\u00a0<a href=\"https:\/\/alders.de\/fr\/industries\/\">Anwendungsfeldern<\/a>\u00a0verwendet. Werden mehrere Drucktaster in einer Gruppe angeordnet, wird von einem Tastenfeld gesprochen. Das wohl bekannteste Beispiel hierf\u00fcr ist die klassische Tastatur, also ein Tastenfeld, das f\u00fcr die Eingabe von W\u00f6rtern sowie Zahlen gedacht ist.<\/p>\n<p>Neben elektrischen Tastern, die mit der Bewegung von Kontakten arbeiten, gibt es ebenfalls nichtelektrische Varianten. Dazu z\u00e4hlen beispielsweise die Tasten eines Klaviers, einer Schreibmaschine oder pneumatische Tasten einer Anlage, die mit Druckluft betrieben wird. Elektrische Drucktaster k\u00f6nnen zus\u00e4tzlich eine Zwei-Ebenen-Schaltung erm\u00f6glichen sowie mit dem Prinzip des Hall-Effekts arbeiten. Letzteres beg\u00fcnstigt eine besonders hohe Langlebigkeit mit mehreren Millionen Schaltzyklen je nach Ausf\u00fchrung des Drucktasters.[\/vc_column_text][vc_btn title=\u00a0\u00bbALDERS Produktportfolio &#8211; Drucktaster\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb link=\u00a0\u00bburl:https%3A%2F%2Falders.de%2Fprodukte%2Fschalter-taster%2Fdrucktaster%2F\u00a0\u00bb el_class=\u00a0\u00bbbutton-white\u00a0\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb el_class=\u00a0\u00bbsection-grauverlauf\u00a0\u00bb][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">IP-Schutzarten f\u00fcr Drucktaster: wasserdicht und staubresistent<\/h2>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner][vc_column_text]Die Klassifizierung von Drucktastern als wasserdicht oder staubresistent erfolgt durch die sogenannten IP-Schutzarten (IP = International Protection\/Ingress Protection). Diese beschreiben den aktiven Schutz eines elektrischen Betriebsmittels gegen\u00fcber dem Eindringen von Wasser oder anderen Fremdk\u00f6rpern sowie Ber\u00fchrungen oder auch die Sto\u00dffestigkeit. Gerade im industriellen Einsatz, in der Medizin oder auch im Milit\u00e4r m\u00fcssen Drucktaster \u00fcber einen sehr langen Zeitraum zuverl\u00e4ssig unter widrigsten Umweltbedingungen jederzeit zuverl\u00e4ssig funktionieren. Feuchtigkeit, \u00d6le, Staub, Schmutz und viele weitere aggressive Medien k\u00f6nnen beim Arbeitseinsatz in Ber\u00fchrung mit den elektrischen Bedienelementen kommen.<\/p>\n<p>Bei dem international genormten IP-Pr\u00fcfverfahren werden Drucktaster und \u00e4hnliche Bauteile auf ihre Tauglichkeit f\u00fcr die angesprochenen Anforderungen getestet. F\u00fcr die Drucktaster, die Sie bei\u00a0<a href=\"https:\/\/alders.de\/fr\/\">ALDERS<\/a>\u00a0erhalten, sind im Wesentlichen die beiden Schutzarten IP64 und IP68 relevant. Die Schutzart IP64 beschreibt, dass ein Drucktaster staubdicht und gegen Ber\u00fchrungen sowie Spritzwasser gesch\u00fctzt ist. IP68 erg\u00e4nzt die genannten Eigenschaften zus\u00e4tzlich um eine erweiterte Wasserdichtheit.<\/p>\n<p>Weitere Schutzma\u00dfnahmen k\u00f6nnen durch zus\u00e4tzliche\u00a0<a href=\"https:\/\/alders.de\/produkte\/schalter-taster\/dichtkappen\/\">Dichtkappen<\/a>\u00a0vorgenommen werden. Au\u00dferdem werden bestimmte Varianten von Drucktastern von Grund auf sehr robust entwickelt und bieten besonderen Schutz gegen\u00fcber Vandalismus. Solche Modelle werden beispielsweise an \u00f6ffentlich zug\u00e4nglichen Schaltungen installiert, wie Aufz\u00fcgen oder elektrischen T\u00fcr\u00f6ffnern.<\/p>\n<p>Ein \u00e4hnliches Funktionsprinzip wie Drucktaster weisen\u00a0<a href=\"https:\/\/alders.de\/fachwissen\/druckschalter\/\">Druckschalter<\/a>\u00a0auf. Anstatt nur kurzzeitig einen Kontakt zu erzeugen, wird dieser nach der Bet\u00e4tigung dauerhaft hergestellt. Solange, bis der Schalter erneut gedr\u00fcckt wird.[\/vc_column_text][vc_btn title=\u00a0\u00bbALDERS Produktportfolio &#8211; Dichtkappen\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb link=\u00a0\u00bburl:https%3A%2F%2Falders.de%2Fprodukte%2Fschalter-taster%2Fdichtkappen%2F\u00a0\u00bb el_class=\u00a0\u00bbbutton-white\u00a0\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"featured_media":0,"template":"","class_list":["post-294636","glossary","type-glossary","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Drucktaster: Funktionsweise, Eigenschaften &amp; Anwendungen<\/title>\n<meta name=\"description\" content=\"Drucktaster und ihre vielf\u00e4ltige Anwendung: Entdecken Sie die Funktion und Einsatzgebiete dieser praktischen Bedienelemente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alders.de\/fr\/glossar\/bouton-poussoir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drucktaster: Funktionsweise, Eigenschaften &amp; Anwendungen\" \/>\n<meta property=\"og:description\" content=\"Drucktaster und ihre vielf\u00e4ltige Anwendung: Entdecken Sie die Funktion und Einsatzgebiete dieser praktischen Bedienelemente.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"ALDERS electronic GmbH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Alders.electronic\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T11:52:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alders.de\/wp-content\/uploads\/2021\/02\/p9-OTTO-Controls-Schalter.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1072\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alders.de\\\/fr\\\/glossar\\\/bouton-poussoir\\\/\",\"url\":\"https:\\\/\\\/alders.de\\\/fr\\\/glossar\\\/bouton-poussoir\\\/\",\"name\":\"Drucktaster: Funktionsweise, Eigenschaften & Anwendungen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alders.de\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alders.de\\\/fr\\\/glossar\\\/bouton-poussoir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alders.de\\\/fr\\\/glossar\\\/bouton-poussoir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alders.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/p9-OTTO-Controls-Schalter-280x300.png\",\"datePublished\":\"2021-02-23T09:04:20+00:00\",\"dateModified\":\"2026-05-26T11:52:58+00:00\",\"description\":\"Drucktaster und ihre vielf\u00e4ltige Anwendung: Entdecken Sie die Funktion und Einsatzgebiete dieser praktischen Bedienelemente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alders.de\\\/fr\\\/glossar\\\/bouton-poussoir\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alders.de\\\/fr\\\/glossar\\\/bouton-poussoir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/alders.de\\\/fr\\\/glossar\\\/bouton-poussoir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alders.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/p9-OTTO-Controls-Schalter-280x300.png\",\"contentUrl\":\"https:\\\/\\\/alders.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/p9-OTTO-Controls-Schalter-280x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alders.de\\\/fr\\\/glossar\\\/bouton-poussoir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ALDERS\",\"item\":\"https:\\\/\\\/alders.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bouton-poussoir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alders.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/alders.de\\\/fr\\\/\",\"name\":\"ALDERS electronic GmbH\",\"description\":\"Der Spezialist f\u00fcr elektromechanische L\u00f6sungen\",\"publisher\":{\"@id\":\"https:\\\/\\\/alders.de\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alders.de\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alders.de\\\/fr\\\/#organization\",\"name\":\"ALDERS electronic GmbH\",\"url\":\"https:\\\/\\\/alders.de\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/alders.de\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alders.de\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Alders-logo-Komplett.png\",\"contentUrl\":\"https:\\\/\\\/alders.de\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Alders-logo-Komplett.png\",\"width\":1043,\"height\":253,\"caption\":\"ALDERS electronic GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/alders.de\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Alders.electronic\\\/\",\"https:\\\/\\\/de.linkedin.com\\\/company\\\/alders-electronic-gmbh\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC-hR66wsAmKOdY03IokrlzA\",\"https:\\\/\\\/www.instagram.com\\\/alders.electronic\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Drucktaster: Funktionsweise, Eigenschaften & Anwendungen","description":"Drucktaster und ihre vielf\u00e4ltige Anwendung: Entdecken Sie die Funktion und Einsatzgebiete dieser praktischen Bedienelemente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alders.de\/fr\/glossar\/bouton-poussoir\/","og_locale":"fr_FR","og_type":"article","og_title":"Drucktaster: Funktionsweise, Eigenschaften & Anwendungen","og_description":"Drucktaster und ihre vielf\u00e4ltige Anwendung: Entdecken Sie die Funktion und Einsatzgebiete dieser praktischen Bedienelemente.","og_url":"\/","og_site_name":"ALDERS electronic GmbH","article_publisher":"https:\/\/www.facebook.com\/Alders.electronic\/","article_modified_time":"2026-05-26T11:52:58+00:00","og_image":[{"width":1000,"height":1072,"url":"https:\/\/alders.de\/wp-content\/uploads\/2021\/02\/p9-OTTO-Controls-Schalter.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alders.de\/fr\/glossar\/bouton-poussoir\/","url":"https:\/\/alders.de\/fr\/glossar\/bouton-poussoir\/","name":"Drucktaster: Funktionsweise, Eigenschaften & Anwendungen","isPartOf":{"@id":"https:\/\/alders.de\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alders.de\/fr\/glossar\/bouton-poussoir\/#primaryimage"},"image":{"@id":"https:\/\/alders.de\/fr\/glossar\/bouton-poussoir\/#primaryimage"},"thumbnailUrl":"https:\/\/alders.de\/wp-content\/uploads\/2021\/02\/p9-OTTO-Controls-Schalter-280x300.png","datePublished":"2021-02-23T09:04:20+00:00","dateModified":"2026-05-26T11:52:58+00:00","description":"Drucktaster und ihre vielf\u00e4ltige Anwendung: Entdecken Sie die Funktion und Einsatzgebiete dieser praktischen Bedienelemente.","breadcrumb":{"@id":"https:\/\/alders.de\/fr\/glossar\/bouton-poussoir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alders.de\/fr\/glossar\/bouton-poussoir\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/alders.de\/fr\/glossar\/bouton-poussoir\/#primaryimage","url":"https:\/\/alders.de\/wp-content\/uploads\/2021\/02\/p9-OTTO-Controls-Schalter-280x300.png","contentUrl":"https:\/\/alders.de\/wp-content\/uploads\/2021\/02\/p9-OTTO-Controls-Schalter-280x300.png"},{"@type":"BreadcrumbList","@id":"https:\/\/alders.de\/fr\/glossar\/bouton-poussoir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ALDERS","item":"https:\/\/alders.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Bouton-poussoir"}]},{"@type":"WebSite","@id":"https:\/\/alders.de\/fr\/#website","url":"https:\/\/alders.de\/fr\/","name":"ALDERS electronic GmbH","description":"Der Spezialist f\u00fcr elektromechanische L\u00f6sungen","publisher":{"@id":"https:\/\/alders.de\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alders.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/alders.de\/fr\/#organization","name":"ALDERS electronic GmbH","url":"https:\/\/alders.de\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/alders.de\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/alders.de\/wp-content\/uploads\/2022\/07\/Alders-logo-Komplett.png","contentUrl":"https:\/\/alders.de\/wp-content\/uploads\/2022\/07\/Alders-logo-Komplett.png","width":1043,"height":253,"caption":"ALDERS electronic GmbH"},"image":{"@id":"https:\/\/alders.de\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Alders.electronic\/","https:\/\/de.linkedin.com\/company\/alders-electronic-gmbh","https:\/\/www.youtube.com\/channel\/UC-hR66wsAmKOdY03IokrlzA","https:\/\/www.instagram.com\/alders.electronic\/"]}]}},"_links":{"self":[{"href":"https:\/\/alders.de\/fr\/wp-json\/wp\/v2\/glossary\/294636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alders.de\/fr\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/alders.de\/fr\/wp-json\/wp\/v2\/types\/glossary"}],"version-history":[{"count":1,"href":"https:\/\/alders.de\/fr\/wp-json\/wp\/v2\/glossary\/294636\/revisions"}],"predecessor-version":[{"id":294638,"href":"https:\/\/alders.de\/fr\/wp-json\/wp\/v2\/glossary\/294636\/revisions\/294638"}],"wp:attachment":[{"href":"https:\/\/alders.de\/fr\/wp-json\/wp\/v2\/media?parent=294636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}